{"id":508,"date":"2011-12-01T14:07:00","date_gmt":"2011-12-01T18:07:00","guid":{"rendered":"http:\/\/www.alquier.org\/linfa\/work\/2011\/12\/01\/lalquier-feedly-is-version-8-available-on-firefox-yet-all-i-can-find-is-6-1\/"},"modified":"2011-12-01T14:07:00","modified_gmt":"2011-12-01T18:07:00","slug":"lalquier-feedly-is-version-8-available-on-firefox-yet-all-i-can-find-is-6-1","status":"publish","type":"post","link":"http:\/\/www.alquier.org\/laurent\/sites\/2011\/12\/01\/lalquier-feedly-is-version-8-available-on-firefox-yet-all-i-can-find-is-6-1\/","title":{"rendered":"@feedly &#8211; is Version 8+ available on Firefox yet ? all I can find is 6.1."},"content":{"rendered":"<p> @feedly &#8211; is Version 8  available on Firefox yet ? all I can find is 6.1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>@feedly &#8211; is Version 8 available on Firefox yet ? all I can find is 6.1.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,1],"tags":[168],"class_list":["post-508","post","type-post","status-publish","format-standard","hentry","category-blog","category-uncategorized","tag-tweet","xfolkentry","clearfix"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8frwa-8c","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/posts\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":0,"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/posts\/508\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/media?parent=508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/categories?post=508"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.alquier.org\/laurent\/sites\/wp-json\/wp\/v2\/tags?post=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}